{"id":29804,"date":"2023-03-15T13:47:53","date_gmt":"2023-03-15T12:47:53","guid":{"rendered":"https:\/\/swigift.ch\/?page_id=29804"},"modified":"2026-04-26T10:38:39","modified_gmt":"2026-04-26T08:38:39","slug":"allgemeine-geschaeftsbedingungen","status":"publish","type":"page","link":"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"29804\" class=\"elementor elementor-29804 elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bc60cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bc60cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31d07a4\" data-id=\"31d07a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d56cd35 elementor-widget elementor-widget-heading\" data-id=\"d56cd35\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"cgv\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Allgemeine Gesch\u00e4ftsbedingungen (AGB)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94bb56e elementor-widget elementor-widget-text-editor\" data-id=\"94bb56e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Allgemeine Gesch\u00e4ftsbedingungen (nachfolgend \u201eAGB\u201c) gelten f\u00fcr alle auf der Website www.swigift.ch (nachfolgend \u201eWebsite\u201c genannt) abgeschlossenen Rechtsgesch\u00e4fte. Diese Website wird von der Firma Swigift Varin (im Folgenden \u201eSwigift\u201c) verwaltet.<\/p><p>Die Allgemeinen Gesch\u00e4fts- und Datenschutzbedingungen sind urheberrechtlich gesch\u00fctzt. Ohne vorherige schriftliche Zustimmung des Autors werden unbefugte Verwendungen dieser Bedingungen verfolgt.<\/p><p><strong>\u00a0<\/strong><\/p><ol><li><h2><strong>Definitionen<\/strong><\/h2><\/li><\/ol><p>In den Allgemeinen Gesch\u00e4fts- und Datenschutzbedingungen haben Angaben, die mit einem Gro\u00dfbuchstaben beginnen, folgende Bedeutung:<\/p><p><b>Benutzer<\/b><b>: <\/b>bezeichnet jede nat\u00fcrliche oder juristische Person, die die Website swigift.ch nutzt und erkl\u00e4rt, eine Person im Alter von mindestens 18 Jahren mit Rechtspers\u00f6nlichkeit zu sein oder, falls dies nicht der Fall ist, \u00fcber eine elterliche Genehmigung bzw. Zustimmung des gesetzlichen Vertreters zu verf\u00fcgen, sodass er auf der Website eine Bestellung aufgeben kann.<\/p><p><b>Partner: <\/b>bezieht sich auf jeden H\u00e4ndler, der mit der Firma Swigift Varin zusammenarbeitet und dessen Produkte \u00fcber die Website Swigift.ch zum Verkauf anbietet<\/p><p><b>Website<\/b>: bezieht sich auf die Website swigift.ch<\/p><p><b>Produkt<\/b><b>(e): <\/b>bezieht sich auf die Produkte, die zum Zeitpunkt der Konsultation und\/oder Bestellung auf der Website angeboten und beschrieben werden.<\/p><p><b>Dienstleistung<\/b><b>(<\/b><b>en<\/b><b>): <\/b>bezieht sich auf die Dienstleistungen, die zum Zeitpunkt der Konsultation und\/oder Bestellung auf der Website angeboten und beschrieben werden.<\/p><p><b>Arbeitstage<\/b><b>: <\/b>entsprechen Wochentagen, mit Ausnahme von Wochenenden und gesetzlichen Feiertagen, die in der f\u00fcr den Hauptsitz von Swigift geltenden kantonalen Gesetzgebung offiziell anerkannt sind.<\/p><ol start=\"2\"><li><h2><strong>Geltungsbereich der Allgemeine Gesch\u00e4ftsbedingungen<\/strong><\/h2><\/li><\/ol><p>Die Swigift-Website ist ein Vertriebsunternehmen, das Geschenkboxen anbietet. Die Nutzung der Website, der Produkte und Dienstleistungen sowie der Vermittlungsleistungen unterliegen ausschlie\u00dflich diesen Allgemeine Gesch\u00e4ftsbedingungen (im Folgenden \u201eAGB\u201c).<\/p><p>Der Zweck dieser AGB besteht darin, die vom BeBenutzer auf der Website aufgegebenen Bestellungen zu regeln. Der Benutzer verpflichtet sich, diese AGB zu respektieren.<\/p><p>Die Registrierung und\/oder die Aufgabe einer Bestellung auf der Website setzt ausdr\u00fccklich die vollst\u00e4ndige Annahme dieser AGB durch den Benutzer voraus. Diese AGB haben Vorrang vor allen anderen spezifischen oder allgemeinen Bedingungen, die nicht ausdr\u00fccklich von Swigift genehmigt wurden.<\/p><p>Swigift beh\u00e4lt sich das Recht vor, seine AGB jederzeit zu \u00e4ndern. In diesem Fall gelten die AGB, die zum Zeitpunkt der Registrierung und\/oder Bestellung durch den Benutzer in Kraft waren. Wenn der Benutzer die AGB bereits bei der Registrierung gelesen hat und nachtr\u00e4glich von Swigift neue AGB eingef\u00fchrt werden, haben letztere Vorrang. Die AGB k\u00f6nnen vom Benutzer jederzeit auf der Website eingesehen werden.<\/p><ol start=\"3\"><li><h2><strong>Zugang und Registrierung zu Diensten<\/strong><\/h2><\/li><\/ol><h3><strong>3.1 Nutzung unserer Dienste<\/strong><\/h3><p>Um die Dienste nutzen zu k\u00f6nnen, m\u00fcssen Sie Zugang zum Internet haben. Etwaige entsprechende Verbindungs-, Abonnement- und Nutzungsgeb\u00fchren gehen ausschlie\u00dflich zu Lasten des Benutzers. Der Benutzer muss \u00fcber die gesamte erforderliche Ausr\u00fcstung verf\u00fcgen. Der Benutzer muss au\u00dferdem \u00fcber die Software und Einstellungen verf\u00fcgen, die f\u00fcr das ordnungsgem\u00e4\u00dfe Funktionieren der Dienste erforderlich sind.<\/p><h3><strong>3.2 Registrierung und Kontoerstellung<\/strong><\/h3><p>Die meisten Dienste erfordern eine Registrierung und Kontoerstellung. Das Registrierungsverfahren ist auf der Website beschrieben. Am Ende des Vorgangs erh\u00e4lt der Benutzer eine Registrierungsbest\u00e4tigungs-E-Mail. Der Benutzer tr\u00e4gt die alleinige Verantwortung f\u00fcr die Wahrung der Vertraulichkeit seiner E-Mail-Adresse und seines Passworts sowie f\u00fcr alle Ma\u00dfnahmen, die im Zusammenhang mit diesem Konto und seinen Daten ergriffen werden. Der Benutzer verpflichtet sich, Swigift unverz\u00fcglich schriftlich (\u00fcber die Kontaktseite auf der Website) \u00fcber jede unbefugte Nutzung seines Kontos und\/oder Passworts und\/oder jede Sicherheitsverletzung zu informieren. Swigift kann nicht f\u00fcr Verluste oder Sch\u00e4den haftbar gemacht werden, die im Falle einer Pflichtverletzung entstehen.<\/p><h3><strong>3.3 Sonderangebote, exklusive Angebote und Gewinnspiele\/Wettbewerbe<br \/><\/strong><\/h3><p>Der Benutzer verpflichtet sich, Sonderangebote, exklusive Angebote (Rabattcodes, Sonderaktionen usw.) und\/oder Gewinnspiele oder Wettbewerbe von Swigift fair und in gutem Glauben zu nutzen und dabei die f\u00fcr jedes Angebot oder jeden Wettbewerb angegebenen besonderen Bedingungen einzuhalten. Im Rahmen dieser Angebote k\u00f6nnen die Verpackung und bestimmte Eigenschaften des Produkts von denen auf der Website oder in den Verkaufsunterlagen abweichen, ohne dass dies Auswirkungen auf die gesetzlichen Garantien f\u00fcr das Produkt hat. Swigift beh\u00e4lt sich das Recht vor, Bestellungen abzulehnen, die aus einer unbefugten oder betr\u00fcgerischen Verbreitung seiner Angebote resultieren.<\/p><ol start=\"4\"><li><h2><strong>Dienstleistungen<\/strong><\/h2><\/li><\/ol><h3><strong>4.1 Das Produkt<\/strong><\/h3><p>Swigift vermarktet seine Geschenkboxen mit:<\/p><p>-Einem Geschenkgutschein, den der Benutzer unter den auf der Website angebotenen Partnern ausw\u00e4hlt.<\/p><p>-Eine Karte, die der Benutzer bei der Bestellung ausgew\u00e4hlt oder selbst gestaltet hat.<\/p><p>-Einem Umschlag, in den die personalisierte oder vordefinierte Karte eingelegt wird.<\/p><p>-Einem Kartenhalter im Lieferumfang enthalten.<\/p><p>Der Benutzer wird dar\u00fcber informiert, dass die auf der Website pr\u00e4sentierten Produkte von der Realit\u00e4t abweichen k\u00f6nnen. Der Kaufvertrag zwischen Swigift, seinen Partnern und dem Benutzer kommt zustande, wenn der Benutzer seine Bestellung online best\u00e4tigt.<\/p><h3><strong>4.2 Geschenkgutschein<\/strong><\/h3><p>Die G\u00fcltigkeitsdauer eines Geschenkgutscheins beginnt mit dem Tag des Versands durch den Vertriebspartner.<\/p><p>Die G\u00fcltigkeitsdauer des Geschenkgutscheins des Partners wird zum Zeitpunkt der Bestellung auf der Website angegeben und kann auch durch den Partner auf dem Geschenkgutschein vermerkt werden.<\/p><p>Der Geschenkgutschein gibt dem Empf\u00e4nger w\u00e4hrend der G\u00fcltigkeitsdauer das Recht, ihn bei dem betreffenden Partner einzul\u00f6sen. Dem Empf\u00e4nger des Geschenkgutscheins wird jedoch empfohlen, diese Information direkt beim Partner zu \u00fcberpr\u00fcfen.<\/p><p>F\u00fcr die Nutzung des Gutscheins sind die AGB des Partners ma\u00dfgeblich. Die auf der Webseite angebotenen Partner sind f\u00fcr die Funktionalit\u00e4t der Geschenkgutscheine w\u00e4hrend der gesamten G\u00fcltigkeitsdauer verantwortlich. Swigift haftet nicht f\u00fcr die \u00dcberschreitung der G\u00fcltigkeitsdauer des Gutscheins.<\/p><p>Geschenkgutscheine sind nicht austauschbar. Eine R\u00fcckerstattung des Wertes des Geschenkgutscheins ist ausgeschlossen.<\/p><h3><strong>4.3 Karte<\/strong><\/h3><p>W\u00e4hrend der Bestellphase kann der Benutzer ob er seine Karte mithilfe der verschiedenen auf der Website angebotenen Optionen und Tools individuell gestalten oder eine vordefinierte, nicht ver\u00e4nderbare Karte w\u00e4hlen m\u00f6chte. Die Karte ist 10 x 15 cm gro\u00df und aus hochwertigem, halbgl\u00e4nzendem Fotopapier gefertigt. Sobald der Benutzer seine Bestellung online best\u00e4tigt, ist eine \u00c4nderung des Fotos nicht mehr m\u00f6glich. Allein der Benutzer ist verantwortlich und verpflichtet sich, diese AGB einzuhalten.<\/p><p>Sofern nicht anders angegeben, erfolgt der Druck durch Swigift, die auch R\u00e4nder anbringen kann, um einen optimalen Druck zu gew\u00e4hrleisten.<\/p><h3><strong>4.4 Umschlag<\/strong><\/h3><p>W\u00e4hrend der Bestellphase werden von Swigift verschiedene Briefumschlagfarben angeboten. Dort wird die personalisierte oder vordefinierte Karte eingelegt.<\/p><h3><strong>4.5 Fotohalter<\/strong><\/h3><p>Ein von Swigift entworfener Holzhalter f\u00fcr die Karte ist in der Geschenkbox enthalten. Der Benutzer kann keinen Anspruch auf Weiterverkauf des Produkts, unabh\u00e4ngig davon, ob er ver\u00e4ndert wurde oder nicht, oder auf einen Umtausch in bar geltend machen.<\/p><h3><strong>4.6 Geschenkbox<\/strong><\/h3><p>Die Geschenkbox wurde von der Firma Swigift und ihren verschiedenen Lieferanten entworfen. Es enth\u00e4lt die in Artikel 4 genannten Produkte. Die Geschenkbox dient dank ihrer Stabilit\u00e4t und ihres Klebestreifens auch als Versandkarton.<\/p><ol start=\"5\"><li><h2><strong>Preis<\/strong><strong style=\"font-size: 16px;\">\u00a0<\/strong><\/h2><\/li><\/ol><h3><strong>5.1 W\u00e4hrung<\/strong><\/h3><p>Alle Preise sind in CHF (Schweizer Franken) angegeben.<\/p><h3><strong>5.2 Preise und S\u00e4tze<\/strong><\/h3><p>Der Preis wird bei der Bestellung f\u00e4llig. Es gelten die aktuellen Preise, die auf der Website angezeigt werden. Die Preise verstehen sich inklusive aller Steuern. Swigift beh\u00e4lt sich das Recht vor, seine Preise jederzeit zu \u00e4ndern, wobei jedoch davon ausgegangen wird, dass f\u00fcr den BeBenutzer ausschlie\u00dflich der am Tag der Bestellbest\u00e4tigung auf der Website angezeigte Preis gilt. Swigift beh\u00e4lt sich das Recht vor, offensichtliche Preisfehler und -\u00e4nderungen vorzunehmen.<\/p><h3><strong>5.3. Geschenkgutscheinpreis<\/strong><\/h3><p>Der Benutzer kann, abh\u00e4ngig von den Leistungen des Partners, den Wert des Gutscheins selbst w\u00e4hlen. Der gew\u00e4hlte Betrag entspricht dem Betrag, der auf den Gutschein geladen wird. <b>Beispiel<\/b><b>: <\/b>Bei einem vom Benutzer bestellten Geschenkgutschein im Wert von 100,00 CHF erh\u00e4lt der Beschenkte den Geschenkgutschein im Wert von 100,00 CHF.<\/p><h3><strong>5.4. Verpackungspreis<\/strong><\/h3><p>Die Verpackungskosten betragen 8.00 CHF. Dieser Preis beinhaltet eine Geschenkbox, die auch als Versandkarton dient, eine hochwertige Holzunterlage f\u00fcr die Karte, eine personalisierte oder vordefinierte Karte, mit einem farbigen Umschlag Ihrer Wahl. Auch der Versand per A-Post ist inbegriffen.<\/p><h3><strong>5.5. Endpreise<\/strong><\/h3><p>Bei der endg\u00fcltigen Bestellung jeder Geschenkbox muss der Benutzer den Betrag des Geschenkgutscheins sowie Verpackungskosten in H\u00f6he von 8,00 CHF bezahlen. <b>Beispiel<\/b><b>: <\/b>Bei einem vom Benutzer bestellten Geschenkgutschein im Wert von 100,00 CHF zahlt der Benutzer bei Abschluss der Bestellung 108,00 CHF. Auf der Website k\u00f6nnen zus\u00e4tzliche Optionen angeboten werden, die jedoch in der Verantwortung des BeBenutzers liegen.<\/p><ol start=\"6\"><li><h2><strong>Best\u00e4tigung von Bestellungen und Endergebnis<\/strong><\/h2><\/li><\/ol><h3><strong>6.1. Pflicht zur Bestellung<\/strong><\/h3><p>Der Benutzer, der auf der Website bestellen m\u00f6chte, muss sich identifizieren und\/oder auf der Website registrieren, indem er die erforderlichen Pflichtfelder ausf\u00fcllt. Er muss au\u00dferdem seine Bestellung best\u00e4tigen, die AGB akzeptieren und die Zahlung gem\u00e4\u00df den angegebenen Bedingungen vornehmen.<\/p><h3><strong>6.2. Best\u00e4tigung der Bestellung<\/strong><\/h3><p>Jede bei Swigift eingegangene Bestellung gilt als verbindlich und endg\u00fcltig und stellt mit der Best\u00e4tigung der Bestellung eine Bestellung dar. Die Best\u00e4tigung der Bestellung erfolgt fast gleichzeitig mit der Validierung der Transaktion durch die sicheren Online-Zahlungsmethoden, die auf der Website verf\u00fcgbar sind. Die Best\u00e4tigung der Bestellung stellt die Zustimmung des Benutzers zu den Merkmalen des Verkaufs dar (Preis, Menge, Art und Format der Produkte und Dienstleistungen, Adressen).<\/p><ul><li>Der Benutzer ist verpflichtet, seine Bestellung zu \u00fcberpr\u00fcfen, bevor er sie best\u00e4tigt. Swigift lehnt jede Verantwortung f\u00fcr Fehler oder Auslassungen seitens des Benutzers ab.<\/li><li>Nach dieser Validierung kann keine \u00c4nderung oder Stornierung einer Bestellung erfolgen.<\/li><li>Der Benutzer wird dar\u00fcber informiert und erkennt an, dass die Fristen erst ab der Best\u00e4tigung der Bestellung laufen, vorbehaltlich der vollst\u00e4ndigen Zahlung des Bestellpreises durch den Benutzer.<\/li><\/ul><h3><strong>6.3. \u00dcberpr\u00fcfung des Endergebnis<\/strong><\/h3><p>Die \u00dcberpr\u00fcfung des Endergebnis aller heruntergeladenen Bilder und anderer Inhalte sowie der am Produkt im Allgemeinen vorgenommenen Anpassungen liegt allein in der Verantwortung des Benutzers. Es obliegt dem Benutzer, die Qualit\u00e4t seiner Fotos und Bilder sowie das Endergebnis der bestellten Produkte entsprechend dem gew\u00e4hlten Format, aber auch der Aufl\u00f6sung sicherzustellen. Swigift \u00fcbernimmt keine Retusche- oder \u00c4nderungsdienste f\u00fcr vom Benutzer bereitgestellte Fotos und\/oder Bilder.<\/p><h3><strong>6.4. Nachweis \u00fcber Bestellungen\/Archivierung<\/strong><\/h3><p>Die aufgezeichneten Daten, best\u00e4tigt durch die Bestellbest\u00e4tigungs-E-Mail, stellen einen Beweis f\u00fcr alle vergangenen Transaktionen dar. Die vom sicheren Zahlungssystem erfassten Daten stellen einen Beweis f\u00fcr Finanztransaktionen dar. Der Benutzer hat daf\u00fcr zu sorgen, dass diese f\u00fcr alle Zwecke sorgf\u00e4ltig aufbewahrt werden. Sofern kein offensichtlicher Fehler vorliegt, den der Benutzer beweisen kann, haben die in den Datenbanken von Swigift gespeicherten Daten Beweiskraft f\u00fcr aufgegebene Bestellungen.<\/p><ol start=\"7\"><li><h2><strong>Beachtung des Inhalts<\/strong><\/h2><\/li><\/ol><p>Der Benutzer wird daran erinnert, dass die im Rahmen der Produkte und Dienstleistungen \u00fcbermittelten personalisierten Kreationen ausschlie\u00dflich in seiner Verantwortung liegen. Der Benutzer erkennt jedoch an, dar\u00fcber informiert zu sein, dass Swigift, wenn sie von einem Dritten oder auf irgendeine Weise auf die Rechtswidrigkeit der \u00fcber die Dienste \u00fcbermittelten Inhalte aufmerksam gemacht wird, diese Inhalte an die f\u00fcr die Durchsetzung des Gesetzes zust\u00e4ndigen Beh\u00f6rden \u00fcbergeben wird, die dies entsprechend behandeln werden. Swigift beh\u00e4lt sich dann das Recht vor, nach Kontaktaufnahme durch eine Justizbeh\u00f6rde den Zugang zu den Diensten des Benutzers zu sperren, der die umstrittenen Inhalte ver\u00f6ffentlicht.<\/p><h3><strong>7.1. Eltern<\/strong><\/h3><p>Eltern werden gebeten, die Nutzung der Produkte und Dienstleistungen durch ihre minderj\u00e4hrigen Kinder zu \u00fcberwachen. Die im Rahmen der Dienste gespeicherten, genutzten und \u00fcbermittelten Dateien unterliegen der alleinigen Verantwortung des Benutzers.<\/p><h3><strong>7.2. Verbot<\/strong><\/h3><p>Dem Benutzer ist es untersagt, verbotene, illegale oder rechtswidrige Daten zu verwenden, zu speichern, herunterzuladen oder zu versenden, die gegen die guten Sitten oder der \u00f6ffentliche Ordnung versto\u00dfen und die Rechte Dritter verletzen oder verletzen k\u00f6nnten. Swigift kann nicht f\u00fcr die Rechtswidrigkeit von Fotos und\/oder Nachrichten im Hinblick auf die geltenden Gesetze und Vorschriften verantwortlich gemacht werden. Dem Benutzer ist es daher untersagt, Fotos und\/oder Nachrichten zu verwenden, zu speichern, herunterzuladen oder zu \u00fcbermitteln, die eine Anstiftung zur Begehung von Verbrechen und Straftaten oder eine Verletzung der Privatsph\u00e4re darstellen k\u00f6nnten, sowie Dateien, die dazu bestimmt sind, verbotene Gegenst\u00e4nde und\/oder Werke zu zeigen. Diese Liste erhebt keinen Anspruch auf Vollst\u00e4ndigkeit.<\/p><h3><strong>7.3. Gesetze und Richtlinien<\/strong><\/h3><p>Der Benutzer verpflichtet sich, alle geltenden Gesetze und Vorschriften zum Verbot der Verbreitung pornografischer, obsz\u00f6ner oder die Menschenw\u00fcrde ernsthaft verletzender Bilder einzuhalten.<\/p><h3><strong>7.4. Stellungnahme<\/strong><\/h3><p>Der Benutzer erkl\u00e4rt, dass er der rechtm\u00e4\u00dfige Eigent\u00fcmer aller im Rahmen der Produkte und Dienstleistungen verwendeten Fotos und Dateien ist und dass diese frei von jeglichen Rechten sind. Der Benutzer darf keine Dateien speichern oder \u00fcbermitteln, die die Eigentumsrechte anderer Personen verletzen, wie zum Beispiel Texte, Bilder, Gesch\u00e4ftsgeheimnisse, interne oder vertrauliche Informationen, wobei diese Aufz\u00e4hlung keinen Anspruch auf Vollst\u00e4ndigkeit erhebt.<\/p><h3><strong>7.5. \u00dcbereinstimmung<\/strong><\/h3><p>Der Benutzer darf ohne deren ausdr\u00fcckliche vorherige Zustimmung keine Fotos und\/oder Informationen aufnehmen oder \u00fcbermitteln, die private oder pers\u00f6nliche Angelegenheiten einer Person offenbaren. Der Benutzer verpflichtet sich sicherzustellen, dass jede dargestellte Person ihr Einverst\u00e4ndnis zur Nutzung und Verbreitung ihres Bildes gegeben hat.<\/p><h3><strong>7.6. Inhalt<\/strong><\/h3><p>Die dem Benutzer zur Verf\u00fcgung gestellten Inhalte unterliegen dem Schutz der zum Zeitpunkt der Bestellung in der Schweiz geltenden gesetzlichen und beh\u00f6rdlichen Bestimmungen. Jede vollst\u00e4ndige oder teilweise Vervielf\u00e4ltigung bedarf der vorherigen schriftlichen Zustimmung des Herausgebers des jeweiligen angebotenen Inhalts.<\/p><ol start=\"8\"><li><h2><strong>Zahlungen<\/strong><\/h2><\/li><\/ol><p>Zahlungen erfolgen ausschlie\u00dflich \u00fcber die auf der Website angebotenen Zahlungsmethoden.<\/p><h3><strong>8.1. Online-Transaktion<\/strong><\/h3><p>Jede Transaktion wird online von dem zust\u00e4ndigen Unternehmen autorisiert. Die Belastung des Kontos erfolgt zum Zeitpunkt des Bestellabschlusses.<\/p><h3><strong>8.2. Zahlung per Bankkarte und Kreditkarten<\/strong><\/h3><p>Bei Zahlungen per Bankkarte werden die Kreditkartendaten mit dem SSL-Protokoll verschl\u00fcsselt und niemals unverschl\u00fcsselt \u00fcber das Netzwerk \u00fcbertragen. Die Zahlung erfolgt direkt an die Bank. Die vom Benutzer best\u00e4tigte Bestellung gilt erst dann als wirksam, wenn die betreffenden Zahlungszentren der Bank ihr Einverst\u00e4ndnis gegeben haben.<\/p><h3><strong>8.2. Zahlungsart TWINT<\/strong><\/h3><p>Der Benutzer kann seine Bestellung \u00fcber TWINT bezahlen, indem er diese Zahlungsmethode ausw\u00e4hlt. Die Bestellung gilt nach Best\u00e4tigung der Zahlung als best\u00e4tigt.<\/p><h3><strong>8.4. Paypal-Zahlungsmethode<\/strong><\/h3><p>Um die Zahlungsmethode Paypal nutzen zu k\u00f6nnen, muss der Benutzer \u00fcber ein Konto bei der Firma PayPal verf\u00fcgen. Bei Zahlung per PayPal gelten die allgemeinen Nutzungsbedingungen von Paypal, die auf deren Website eingesehen werden k\u00f6nnen. Im Falle einer Stornierung einer aufgeschobenen Zahlung auf Anfrage des Benutzers ohne triftigen Grund beh\u00e4lt sich Swigift das Recht vor, die Bestellung zu stornieren oder vom Benutzer eine Zahlung f\u00fcr die Bestellung zu verlangen. Beschwerden und Streitigkeiten \u00fcber Paypal werden gem\u00e4\u00df dem geltenden Paypal-Verfahren beigelegt.<\/p><h3><strong>8.5. Ablehnung<\/strong><\/h3><p>Im Falle einer Ablehnung durch diese Zentren wird die Bestellung automatisch storniert.<\/p><ol start=\"9\"><li><h2><strong>Nichtbezahlung<\/strong><\/h2><\/li><\/ol><p>Im Falle einer Nichtzahlung kann der Nutzer weder ein Eigentumsrecht an der Bestellung geltend machen noch die Einhaltung einer Frist verlangen. Swigift beh\u00e4lt sich das Recht vor, sich zu weigern, eine Lieferung auszuf\u00fchren oder eine Bestellung eines Verbrauchers zu erf\u00fcllen, der eine fr\u00fchere Bestellung ganz oder teilweise nicht beglichen hat oder mit dem ein Zahlungsstreit anh\u00e4ngig ist.<\/p><ol start=\"10\"><li><h2><strong>Lieferung<\/strong><\/h2><\/li><\/ol><h3><strong>10.1. Lieferland<\/strong><\/h3><p>Die Lieferung der Produkte ist nur in der Schweiz geplant.<\/p><h3><strong>10.2. Lieferadresse<\/strong><\/h3><p>Bestellungen werden an die vom Benutzer bei der Bestellung angegebene Zieladresse geliefert. Der Versand der Produkte in die ganze Schweiz ist je nach logistischen Gegebenheiten m\u00f6glich. Jeder Fehler oder jede Auslassung in der vom Benutzer angegebenen Lieferadresse, die dazu f\u00fchrt, dass die Bestellung nicht versandt werden kann, wird vom Benutzer vorbehaltlich der Bestimmungen dieser AGB finanziell \u00fcbernommen.<\/p><h3><strong>10.3. Lieferungsversp\u00e4tung<\/strong><\/h3><p><strong>10.3.1. Versandart<\/strong><\/p><p>Versandart A ist in der Bestellung enthalten. Auf der Website k\u00f6nnen zus\u00e4tzliche Lieferoptionen angeboten werden, die jedoch in der Verantwortung des Benutzers liegen.<\/p><p>Alle Bestellungen, die <span style=\"text-decoration: underline;\"><strong>vor 16.00 Uhr von Montag bis Freitag (au\u00dfer an Feiertagen)<\/strong><\/span> eingehen, k\u00f6nnen noch am selben Tag versendet werden. Die Zustellung erfolgt durch die Schweizerische Post an einem entsprechenden n\u00e4chsten Werktag, einschliesslich Samstag. Der Zeitpunkt der Verteilung kann jedoch je nach nationalen oder regionalen Feiertagen variieren. <strong>Ein Lieferdatum, das au\u00dferhalb der Zustelltage gew\u00e4hlt wird, wird auf den n\u00e4chsten Werktag verschoben<\/strong>. Swigift lehnt jede Haftung im Falle einer versp\u00e4teten Lieferung ab. Dem Benutzer wird empfohlen, Feiertage vorherzusehen und sich \u00fcber m\u00f6gliche Feiertage und andere zu informieren.<\/p><p><strong>10.3.2. Lieferverz\u00f6gerungen<\/strong><\/p><p>Bei \u00dcberschreitung der Lieferfrist kann Swigift keine Entsch\u00e4digung, Stornierung oder R\u00fcckerstattung der aktuellen Bestellung anbieten. Wenn die Verz\u00f6gerung durch den Benutzer, den Empf\u00e4nger oder einen Dritten verursacht wurde oder auf h\u00f6here Gewalt zur\u00fcckzuf\u00fchren ist. Swigift kann nicht haftbar gemacht werden. Als F\u00e4lle h\u00f6herer Gewalt gelten insbesondere Verz\u00f6gerungen, St\u00f6rungen oder Streiks bei Lieferdiensten, Transportmitteln und\/oder Kommunikationsmitteln sowie Ausf\u00e4lle von Computern. Die Liste ist nicht vollst\u00e4ndig.<\/p><p><strong>10.3.3. Produktverteilung\/-zustellung<\/strong><\/p><p>Die Zustellung erfolgt durch die Post. Beim Versand des Pakets tr\u00e4gt der Benutzer die alleinige Verantwortung f\u00fcr die Zustellung des Pakets an den Empf\u00e4nger. Bei einer Zustellungsanzeige muss der Empf\u00e4nger mit einem Ausweisdokument zur Post gehen. Bei Verlust oder Diebstahl von Paketen kann Swigift nicht haftbar gemacht werden. Im Falle einer unvollst\u00e4ndigen Adresse, einer falschen Adresse, der Ablehnung des Pakets durch den Empf\u00e4nger oder fehlender Informationen, die dazu f\u00fchren, dass das Produkt nicht rechtzeitig an den Empf\u00e4nger geliefert werden kann, kann Swigift nicht f\u00fcr die endg\u00fcltige Qualit\u00e4t dieser Lieferung verantwortlich gemacht werden. Wenn dieser Mangel an Informationen dazu f\u00fchrt, dass dem Empf\u00e4nger eine zweite Lieferung vorgelegt wird, ist Swigift berechtigt, vom Kunden die Kosten f\u00fcr diese zweite Lieferung zu verlangen.<\/p><ol start=\"11\"><li><h2><strong>Beschwerden<\/strong><\/h2><\/li><\/ol><p>Wenn trotz aller Aufmerksamkeit, die Swigift darauf verwendet, die Erwartungen seiner Benutzer zu erf\u00fcllen, die gelieferten Produkte nicht den berechtigten Erwartungen an Qualit\u00e4t und Service entsprechen, f\u00fcr die Swigift in diesen AGB keine ausdr\u00fccklichen Haftungsausschl\u00fcsse definiert hat. Der Benutzer kann eine Beschwerde \u00fcber die Kontaktadresse einreichen.<\/p><h3><strong>11.1. Beschwerde \u00fcber Personalisierung<\/strong><\/h3><p>Swigift kann keine Reklamationen im Zusammenhang mit den Personalisierungselementen, die den vom Benutzer individuell anpassbaren Artikeln oder der vom Benutzer angegebenen Lieferadresse frei hinzugef\u00fcgt werden, positiv annehmen.<\/p><h3><strong>11.2. Ansprechpartner f\u00fcr Beschwerden<\/strong><\/h3><p>Der Benutzer muss jede berechtigte Reklamation per E-Mail unter Angabe der Bestellnummer, des Reklamationsgrunds und der Beweise (Foto, Video, z. B. im Falle eines Qualit\u00e4tsproblems usw.) einreichen. Eine berechtigte Beschwerde f\u00fchrt zur Kontaktaufnahme mit Swigift.<\/p><ol start=\"12\"><li><h2><strong>R\u00fcckgaberecht<\/strong><\/h2><\/li><\/ol><p>Der Benutzer wird dar\u00fcber informiert, dass er gem\u00e4\u00df den geltenden und zwingenden gesetzlichen und\/oder beh\u00f6rdlichen Bestimmungen kein R\u00fcckgabe- oder Umtauschrecht in Anspruch nehmen kann.<\/p><ol start=\"13\"><li><h2><strong>Verantwortlichkeiten<\/strong><\/h2><\/li><\/ol><h3><strong>13.1. Nutzung von Diensten<\/strong><\/h3><p>Die Dienste sind ausschlie\u00dflich der privaten Nutzung vorbehalten, es sei denn, Swigift stimmt ausdr\u00fccklich zu. Der Benutzer verpflichtet sich daher, nur Dateien von Amateurfotoarbeiten zu versenden, die per Definition keinen kommerziellen Wert haben und daher nicht f\u00fcr kommerzielle oder lukrative Zwecke bestimmt sind, es sei denn, Swigift hat ausdr\u00fccklich zugestimmt.<\/p><h3><strong>13.2. Schaden<\/strong><\/h3><p>Swigift kann nicht f\u00fcr indirekte Sch\u00e4den haftbar gemacht werden, die dem BeBenutzer durch die Bereitstellung der Produkte oder die Nutzung der Dienste entstehen.<\/p><h3><strong>13.3. Nichteinhaltung der Allgemeine Gesch\u00e4ftsbedingungen<\/strong><\/h3><p>Der Benutzer verpflichtet sich, Swigift f\u00fcr alle Anfragen, Anspr\u00fcche oder Verurteilungen zu entsch\u00e4digen und\/oder zur\u00fcckzuzahlen, denen Swigift aufgrund der Nichteinhaltung dieser AGB und\/oder der \u00fcber die Produkte und Dienste \u00fcbermittelten Nachrichten ausgesetzt sein k\u00f6nnte. Swigift beh\u00e4lt sich das Recht vor, jederzeit alle oder einen Teil der Produkte und Dienste vor\u00fcbergehend oder dauerhaft zu \u00e4ndern oder zu unterbrechen, ohne die Benutzer im Voraus dar\u00fcber informieren zu m\u00fcssen, und\/oder ihre Benutzerkonten zu schlie\u00dfen. Swigift kann gegen\u00fcber Benutzern oder Dritten nicht f\u00fcr \u00c4nderungen, Aussetzungen oder Unterbrechungen der Dienste haftbar gemacht werden.<\/p><ol start=\"14\"><li><h2><strong>Salvatorische Klausel<\/strong><\/h2><\/li><\/ol><p>Sollten einzelne Bestimmungen dieser AGB ganz oder teilweise nichtig und\/oder veraltet sein, bleibt die G\u00fcltigkeit und\/oder Wirksamkeit der \u00fcbrigen Bestimmungen oder Teile dieser \u00fcbrigen Bestimmungen davon unber\u00fchrt. Ung\u00fcltige und\/oder unwirksame Bestimmungen werden durch solche ersetzt, die dem Sinn und Zweck der ung\u00fcltigen und\/oder unwirksamen Bestimmungen am n\u00e4chsten kommen. Gleiches gilt f\u00fcr m\u00f6gliche Regelungsl\u00fccken.<strong>\u00a0<\/strong><\/p><ol start=\"15\"><li><h2><strong>Kontoschliessung<\/strong><\/h2><\/li><\/ol><p>Der Benutzer kann sein Konto jederzeit schlie\u00dfen. In diesem Zusammenhang werden alle Daten zu diesem Konto schnellstm\u00f6glich gel\u00f6scht. Dar\u00fcber hinaus beh\u00e4lt sich Swigift das Recht vor, jedes Konto eines Benutzers, der die Bestimmungen dieser AGB nicht einh\u00e4lt, ohne Entsch\u00e4digung oder Mitteilung zu schlie\u00dfen.<\/p><ol start=\"16\"><li><h2><strong>Anwendbares Recht und Gerichtsstand<\/strong><\/h2><\/li><\/ol><p>Alle Streitigkeiten mit Swigift im Zusammenhang mit diesen AGB, unterliegen dem Schweizer Recht. Im Falle von Widerspr\u00fcchen ist ausschliesslich die franz\u00f6sische Version dieser AGB massgebend. Es gilt ausschliesslich Schweizer Recht.<\/p><p>Im Falle einer gesetzlichen Verpflichtung oder eines Versto\u00dfes gegen diese AGB beh\u00e4lt sich Swigift das Recht vor, die personenbezogenen Daten des Benutzers offenzulegen,<\/p><p>Der Gerichtsstand befindet sich in Del\u00e9mont, Jura. Swigift ist berechtigt, einen Antrag am Wohnsitz des Benutzers zu stellen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3517c6e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3517c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5dea2a elementor-widget elementor-widget-heading\" data-id=\"f5dea2a\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"protection\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datenschutz <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05df578 elementor-widget elementor-widget-text-editor\" data-id=\"05df578\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><h2><strong>Schutz personenbezogener Daten<\/strong><\/h2><\/li><\/ol><p>Swigift hat sich bem\u00fcht, alle n\u00fctzlichen und notwendigen Ma\u00dfnahmen zu ergreifen, um die Vertraulichkeit und Sicherheit der Daten zu gew\u00e4hrleisten. Es wurden geeignete organisatorische und technische Ma\u00dfnahmen getroffen, um deren Besch\u00e4digung, Zerst\u00f6rung oder unberechtigten Zugriff Dritter zu verhindern.<\/p><ol start=\"2\"><li><h2><strong>Verwendung personenbezogener Daten<\/strong><\/h2><\/li><\/ol><p>Bei der Bestellung ist die Angabe mehrerer Informationen durch den Benutzer erforderlich. Diese Informationen sind f\u00fcr die Bearbeitung von Bestellungen sowie f\u00fcr die Verwaltung und \u00dcberwachung der Gesch\u00e4ftsbeziehung zwischen Swigift und seinen Benutzern unerl\u00e4sslich.<\/p><p>Die personenbezogenen Daten des Benutzers werden zu Analyse- und Statistikzwecken f\u00fcr die Dauer der Gesch\u00e4ftsbeziehung gespeichert. Diese Informationen und Daten erm\u00f6glichen es, das Angebot zu verbessern, um den Erwartungen und Bed\u00fcrfnissen des Benutzers bestm\u00f6glich gerecht zu werden.<\/p><p>Im Rahmen der Auftragsabwicklung haben unsere Partner nur Zugriff auf die f\u00fcr die Erbringung ihrer Leistungen erforderlichen personenbezogenen Daten und sind nicht berechtigt, diese f\u00fcr andere Zwecke zu verwenden.<\/p><ol start=\"3\"><li><h2><strong>Sonstige Daten<\/strong><\/h2><\/li><\/ol><p>Swigift ist berechtigt, die Daten des Benutzers zu verwenden, um ihm Angebote f\u00fcr Produkte oder Dienstleistungen zuzusenden, die den bereits bestellten \u00e4hneln.<\/p><ol start=\"4\"><li><h2><strong>Lagerung<\/strong><\/h2><\/li><\/ol><p>Der BeBenutzer erkennt an, dar\u00fcber informiert zu sein, dass Swigift die vom BeBenutzer online ver\u00f6ffentlichten Daten speichert. Swigift ist berechtigt, diese zu Beweiszwecken aufzubewahren. Eine Mindestaufbewahrungsfrist hierf\u00fcr kann der Benutzer jedoch nicht geltend machen.<\/p><ol start=\"5\"><li><h2><strong>Analysieren<\/strong><\/h2><\/li><\/ol><p>Swigift kann ein Analysesystem verwenden, das darauf abzielt, das Benutzerverhalten auf der Website \u201ewww.swigift.ch\u201c und der soziale\u00a0 Netzwerke zu verstehen.<\/p><ol start=\"6\"><li><h2><strong>Link zu Plattformen Dritter<\/strong><\/h2><\/li><\/ol><p>Die Swigift-Website und die sozialen Netzwerke k\u00f6nnen Links zu Plattformen, Anwendungen und sozialen Netzwerken Dritter enthalten (nicht ersch\u00f6pfende Liste). Der Zugriff auf diese verschiedenen Kan\u00e4le erfolgt unter der alleinigen Verantwortung des Benutzers, der den Vertraulichkeitsrichtlinien der betreffenden Plattformen unterliegt.<\/p><ol start=\"7\"><li><h2><strong>Site-Schutz<\/strong><\/h2><\/li><\/ol><p>Der gesamte Inhalt der Website ist urheberrechtlich gesch\u00fctzt und bleibt ausschlie\u00dfliches Eigentum von Swigift. Keiner der Inhalte, die auf der Website erscheinen oder verf\u00fcgbar sind, darf ohne die vorherige schriftliche Zustimmung von Swigift ganz oder teilweise kopiert, reproduziert, dargestellt, verwendet, erneut ver\u00f6ffentlicht, heruntergeladen, \u00fcbertragen, gepostet oder verteilt werden . Durch den Zugriff auf die Website und deren Nutzung werden keine Rechte \u00fcbertragen, und jede Nutzung, die nicht ausdr\u00fccklich im Voraus von Swigift genehmigt wurde, kann rechtliche Schritte nach sich ziehen.<\/p><ol start=\"8\"><li><h2><strong>Protokolldateien<\/strong><\/h2><\/li><\/ol><p>Wenn Sie diese Website nutzen, erfassen Webserver Nutzungsdaten. Protokolldateien geben Auskunft \u00fcber Ihre IP-Adresse, die zuletzt besuchte Seite, den verwendeten Browser, Datum, Uhrzeit und die angeforderte Datei.<\/p><ol start=\"9\"><li><h2><strong>Cookies<\/strong><\/h2><\/li><\/ol><p>Auf verschiedenen Internetseiten verwendet Swigift Cookies, um den Besuch der Website attraktiver zu gestalten und um bestimmte Funktionen zu erm\u00f6glichen. Diese Cookies erm\u00f6glichen das reibungslose Funktionieren der Website.<\/p><p>Swigift gibt au\u00dferdem Informationen \u00fcber Ihre Nutzung der Website an seine Partner f\u00fcr soziale Medien, Werbung und Analysen weiter, die diese m\u00f6glicherweise mit anderen Informationen kombinieren, die Sie ihnen bereitgestellt haben oder die sie w\u00e4hrend Ihrer Nutzung ihrer Dienste gesammelt haben.<\/p><p>Das Gesetz besagt, dass wir Cookies nur dann auf Ihrem Ger\u00e4t speichern d\u00fcrfen, wenn sie f\u00fcr das Funktionieren dieser Website unbedingt erforderlich sind. F\u00fcr alle anderen Arten von Cookies ben\u00f6tigen wir Ihre Zustimmung.<\/p><p>Ihre Einwilligung gilt f\u00fcr folgender Domain: swigift.ch<\/p><ol start=\"10\"><li><h2><strong>\u00c4nderungen<\/strong><\/h2><\/li><\/ol><p>Swigift beh\u00e4lt sich das Recht vor, dieses Dokument jederzeit zu \u00e4ndern. Die vorgenommenen \u00c4nderungen werden wirksam, sobald sie auf der Website ver\u00f6ffentlicht werden.<\/p><p><em><strong>Ge\u00e4ndert am 26.04.2026<\/strong><\/em><\/p><p>Im Falle von Widerspr\u00fcchen ist ausschlie\u00dflich die franz\u00f6sische Fassung massgeblich<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8242dee elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8242dee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18e5f13 elementor-widget elementor-widget-heading\" data-id=\"18e5f13\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"mentions\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rechtliche Hinweise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d82572 elementor-widget elementor-widget-text-editor\" data-id=\"0d82572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table id=\"9b73a475-ef9c-419b-b18b-8adc516ee0b8\" class=\"simple-table\"><tbody><tr id=\"e1d59efe-738f-4d89-8be6-c68b7514c8c4\"><td id=\"B\\TW\" class=\"\">Name, Vorname des Besitzers der Website<\/td><td id=\":BpF\" class=\"\">Varin Caroline<\/td><\/tr><tr id=\"445eafee-4c4e-401d-9b04-b1441acb759b\"><td id=\"B\\TW\" class=\"\">Adresse des Besitzers der Website \/ Hauptsitz des Unternehmens<\/td><td id=\":BpF\" class=\"\">Chemin de la Fenatte 12, 2824 Vicques<\/td><\/tr><tr id=\"6406b6d2-2c73-4cf9-88b1-6798f1e2da0e\"><td id=\"B\\TW\" class=\"\">IDE-Nr. des Unternehmens<\/td><td id=\":BpF\" class=\"\">CHE-309.525.138<\/td><\/tr><tr id=\"8f34f23f-bb0a-4c6a-90c8-94a55df005ce\"><td id=\"B\\TW\" class=\"\">Kontakt E-Mail<\/td><td id=\":BpF\" class=\"\">info@swigift.ch<\/td><\/tr><tr id=\"23c3efb2-3f25-43bb-91e5-2749f3b35643\"><td id=\"B\\TW\" class=\"\">Website gehostet bei<\/td><td id=\":BpF\" class=\"\">Infomaniak SA<\/td><\/tr><tr id=\"8a604b58-5c5a-49ae-8bab-09f462a537f2\"><td id=\"B\\TW\" class=\"\">Website erstellt von<\/td><td id=\":BpF\" class=\"\"><a href=\"https:\/\/slowane.ch\/\" target=\"_blank\" rel=\"noopener\">www.slowane.ch<\/a> &#8211; Sloane Wolff<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Allgemeine Gesch\u00e4ftsbedingungen (AGB) Die Allgemeine Gesch\u00e4ftsbedingungen (nachfolgend \u201eAGB\u201c) gelten f\u00fcr alle auf der Website www.swigift.ch (nachfolgend \u201eWebsite\u201c genannt) abgeschlossenen Rechtsgesch\u00e4fte. Diese Website wird von der Firma Swigift Varin (im Folgenden \u201eSwigift\u201c) verwaltet. Die Allgemeinen Gesch\u00e4fts- und Datenschutzbedingungen sind urheberrechtlich gesch\u00fctzt. Ohne vorherige schriftliche Zustimmung des Autors werden unbefugte Verwendungen dieser Bedingungen verfolgt. \u00a0 Definitionen In [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-29804","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allgemeine Gesch\u00e4ftsbedingungen - Swigift Boites cadeaux - bon cadeau et carte cadeau personnalis\u00e9e - livraison rapide Suisse<\/title>\n<meta name=\"description\" content=\"Boites cadeaux livr\u00e9es rapidement en Suisse, contenant un bon cadeau de votre choix, une carte de voeux personnalis\u00e9e et enveloppe \u00e0 choix !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allgemeine Gesch\u00e4ftsbedingungen - Swigift Boites cadeaux - bon cadeau et carte cadeau personnalis\u00e9e - livraison rapide Suisse\" \/>\n<meta property=\"og:description\" content=\"Boites cadeaux livr\u00e9es rapidement en Suisse, contenant un bon cadeau de votre choix, une carte de voeux personnalis\u00e9e et enveloppe \u00e0 choix !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Swigift\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Swigift\/61558610159800\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-26T08:38:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"21\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/\",\"url\":\"https:\\\/\\\/swigift.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/\",\"name\":\"Allgemeine Gesch\u00e4ftsbedingungen - Swigift Boites cadeaux - bon cadeau et carte cadeau personnalis\u00e9e - livraison rapide Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/#website\"},\"datePublished\":\"2023-03-15T12:47:53+00:00\",\"dateModified\":\"2026-04-26T08:38:39+00:00\",\"description\":\"Boites cadeaux livr\u00e9es rapidement en Suisse, contenant un bon cadeau de votre choix, une carte de voeux personnalis\u00e9e et enveloppe \u00e0 choix !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/swigift.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/allgemeine-geschaeftsbedingungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/swigift.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allgemeine Gesch\u00e4ftsbedingungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/swigift.ch\\\/de\\\/\",\"name\":\"Swigift\",\"description\":\"personalisierte Geschenke aus der Ferne\",\"publisher\":{\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/swigift.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/#organization\",\"name\":\"Id\u00e9e cadeau originale suisse, une boite contenant un bon cadeau local, une carte de voeux personnalis\u00e9e et plus encore\",\"alternateName\":\"Boites cadeaux personnalis\u00e9es avec bon cadeau commerces Suisse et carte de voeux personnalis\u00e9e, livraison rapide en Suisse.\",\"url\":\"https:\\\/\\\/swigift.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/swigift.ch\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/swigift-logo-carte.png\",\"contentUrl\":\"https:\\\/\\\/swigift.ch\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/swigift-logo-carte.png\",\"width\":300,\"height\":412,\"caption\":\"Id\u00e9e cadeau originale suisse, une boite contenant un bon cadeau local, une carte de voeux personnalis\u00e9e et plus encore\"},\"image\":{\"@id\":\"https:\\\/\\\/swigift.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Swigift\\\/61558610159800\\\/\",\"https:\\\/\\\/www.instagram.com\\\/swigift.ch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/swigift\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allgemeine Gesch\u00e4ftsbedingungen - Swigift Boites cadeaux - bon cadeau et carte cadeau personnalis\u00e9e - livraison rapide Suisse","description":"Boites cadeaux livr\u00e9es rapidement en Suisse, contenant un bon cadeau de votre choix, une carte de voeux personnalis\u00e9e et enveloppe \u00e0 choix !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/","og_locale":"de_DE","og_type":"article","og_title":"Allgemeine Gesch\u00e4ftsbedingungen - Swigift Boites cadeaux - bon cadeau et carte cadeau personnalis\u00e9e - livraison rapide Suisse","og_description":"Boites cadeaux livr\u00e9es rapidement en Suisse, contenant un bon cadeau de votre choix, une carte de voeux personnalis\u00e9e et enveloppe \u00e0 choix !","og_url":"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/","og_site_name":"Swigift","article_publisher":"https:\/\/www.facebook.com\/people\/Swigift\/61558610159800\/","article_modified_time":"2026-04-26T08:38:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"21\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/","url":"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/","name":"Allgemeine Gesch\u00e4ftsbedingungen - Swigift Boites cadeaux - bon cadeau et carte cadeau personnalis\u00e9e - livraison rapide Suisse","isPartOf":{"@id":"https:\/\/swigift.ch\/de\/#website"},"datePublished":"2023-03-15T12:47:53+00:00","dateModified":"2026-04-26T08:38:39+00:00","description":"Boites cadeaux livr\u00e9es rapidement en Suisse, contenant un bon cadeau de votre choix, une carte de voeux personnalis\u00e9e et enveloppe \u00e0 choix !","breadcrumb":{"@id":"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swigift.ch\/de\/allgemeine-geschaeftsbedingungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swigift.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Allgemeine Gesch\u00e4ftsbedingungen"}]},{"@type":"WebSite","@id":"https:\/\/swigift.ch\/de\/#website","url":"https:\/\/swigift.ch\/de\/","name":"Swigift","description":"personalisierte Geschenke aus der Ferne","publisher":{"@id":"https:\/\/swigift.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swigift.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swigift.ch\/de\/#organization","name":"Id\u00e9e cadeau originale suisse, une boite contenant un bon cadeau local, une carte de voeux personnalis\u00e9e et plus encore","alternateName":"Boites cadeaux personnalis\u00e9es avec bon cadeau commerces Suisse et carte de voeux personnalis\u00e9e, livraison rapide en Suisse.","url":"https:\/\/swigift.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swigift.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/swigift.ch\/wp-content\/uploads\/2024\/02\/swigift-logo-carte.png","contentUrl":"https:\/\/swigift.ch\/wp-content\/uploads\/2024\/02\/swigift-logo-carte.png","width":300,"height":412,"caption":"Id\u00e9e cadeau originale suisse, une boite contenant un bon cadeau local, une carte de voeux personnalis\u00e9e et plus encore"},"image":{"@id":"https:\/\/swigift.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Swigift\/61558610159800\/","https:\/\/www.instagram.com\/swigift.ch\/","https:\/\/www.linkedin.com\/company\/swigift\/"]}]}},"_links":{"self":[{"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/pages\/29804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/comments?post=29804"}],"version-history":[{"count":3,"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/pages\/29804\/revisions"}],"predecessor-version":[{"id":40358,"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/pages\/29804\/revisions\/40358"}],"wp:attachment":[{"href":"https:\/\/swigift.ch\/de\/wp-json\/wp\/v2\/media?parent=29804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}